{"id":5133,"date":"2024-10-01T09:05:49","date_gmt":"2024-10-01T07:05:49","guid":{"rendered":"http:\/\/esomus.com\/?post_type=job_listing&#038;p=5133"},"modified":"2024-10-15T11:38:19","modified_gmt":"2024-10-15T09:38:19","slug":"informaticienne-pour-le-deploiement-dun-logiciel-informatique-h-f-x","status":"publish","type":"job_listing","link":"https:\/\/esomus.com\/index.php\/poste\/informaticienne-pour-le-deploiement-dun-logiciel-informatique-h-f-x\/","title":{"rendered":"Int\u00e9grateur logiciel (H\/F\/X)"},"content":{"rendered":"<p>Offre d\u2019emploi\u00a0: <strong>Int\u00e9grateur logiciel informatique (H\/F\/X)<\/strong><\/p>\n<p><strong>ESOMUS<\/strong><\/p>\n<p>Suites aux nombreux contrats en cours avec nos nouveaux clients et existants, nous sommes \u00e0 la recherche de nouveaux talents, nous recherchons actuellement d\u2019un informaticien pour assistez au d\u00e9ploiement des produits logiciels d\u2019 ESOMUS et\/ou de leurs fonctionnalit\u00e9s chez nos clients. Vous aurez de bonnes affinit\u00e9s avec l\u2019informatique et une compr\u00e9hension de la pr\u00e9vention.<\/p>\n<p>Aujourd&#8217;hui, notre soci\u00e9t\u00e9 a d\u00e9velopp\u00e9 plusieurs logiciels permettant d&#8217;aider les entreprises et les ind\u00e9pendants \u00e0 r\u00e9ussir leurs objectifs dans la pr\u00e9vention ainsi que la gestion des risques selon les impositions l\u00e9gales de divers obligations ou de normes de leur entreprise.<\/p>\n<p>Notre entreprise vous permettra de r\u00e9aliser vos ambitions et de vous \u00e9panouir dans un cadre de travail dynamique et d&#8217;opportunit\u00e9s. En rejoignant notre soci\u00e9t\u00e9, vous \u00e9voluerez dans une \u00e9quipe \u00e0 taille humaine o\u00f9 l&#8217;accent est mis sur le d\u00e9veloppement, la formation et le maintien d&#8217;un \u00e9quilibre avec votre vie personnelle.<\/p>\n<p><strong>La mission \/ votre objectif<\/strong><\/p>\n<p>Vous serez incorpor\u00e9(e)dans la cellule d\u2019int\u00e9gration logiciel<br \/>\nVous assister les clients dans leurs entreprises<br \/>\nVous participer avec les responsables au d\u00e9ploiement du logiciel.<br \/>\nVous prenez une part importante aux projets clients.<br \/>\nParam\u00e9trages sp\u00e9cifiques chez les clients ou les utilisateurs<br \/>\nVous faite remontez les demandes clients et les prenez en charges comme :<\/p>\n<ul>\n<li>\u00c9dition, cr\u00e9ation des \u00e9crans,<\/li>\n<li>\u00c9dition, cr\u00e9ation des web rapports<\/li>\n<li>\u00c9dition, cr\u00e9ation Mod\u00e8les de documents<\/li>\n<li>Formations utilisateurs<\/li>\n<\/ul>\n<p>Vous effectuez le reporting journali\u00e8rement vers la direction ou le service IT d\u2019ESOMUS<br \/>\nVous intervenez dans les projets et le suivi du client et de ses demandes<br \/>\nVous maintenez une relation client et de sa partie administrative<br \/>\nVous travaillez du bureau et\/ou chez le client et\/ou en t\u00e9l\u00e9travail selon les r\u00e8gles<\/p>\n<p><strong>Votre profil<\/strong><\/p>\n<p>Vous aurez des affinit\u00e9s avec\u00a0:<\/p>\n<ul>\n<li>L\u2019informatique par le d\u00e9ploiement et la mise en place d\u2019un logiciel\n<ul>\n<li>HTML \/ MSQL \/ base de donnes<\/li>\n<\/ul>\n<\/li>\n<li>Compr\u00e9hension avec la pr\u00e9vention \/ gestion des risques<\/li>\n<\/ul>\n<p>Votre capacit\u00e9 d&#8217;auto-apprentissage, vous permet de trouver des solutions de fa\u00e7on autonome face \u00e0 de nouveaux d\u00e9fis.<br \/>\nVous \u00eates \u00e0 la recherche d&#8217;une fonction vari\u00e9e et vous \u00eates int\u00e9ress\u00e9s \u00e0 relever de nouveaux challenges.<br \/>\nVous \u00eates dynamique, r\u00e9sistant au stress et vous avez l&#8217;esprit d&#8217;\u00e9quipe.<br \/>\nVous avez des projets que vous souhaitez nous montrer.<\/p>\n<p><strong>Langues<\/strong><\/p>\n<ul>\n<li>Fran\u00e7ais<\/li>\n<li>N\u00e9erlandais<\/li>\n<li>Anglais est un atout compl\u00e9mentaire<\/li>\n<li>Autres langues est \u00e9galement un atout compl\u00e9mentaire<\/li>\n<\/ul>\n<p><strong>Date d\u2019entr\u00e9e<\/strong><\/p>\n<ul>\n<li>Selon nos discussions et opportunit\u00e9s<\/li>\n<\/ul>\n<p><strong>R\u00e9gime de travail<\/strong><\/p>\n<ul>\n<li>PFI possible<\/li>\n<li>CDD, ensuite CDI<\/li>\n<li>Temps plein de jour<\/li>\n<\/ul>\n<p><strong>L&#8217;offre<\/strong><\/p>\n<ul>\n<li>Salaire en fonction<\/li>\n<li>Formations afin de devenir un expert dans votre domaine<\/li>\n<\/ul>\n<p><strong>Lieu de travail<\/strong><\/p>\n<ul>\n<li>Li\u00e8ge<\/li>\n<li>Possibilit\u00e9 de t\u00e9l\u00e9travail (suivant les r\u00e8gles impos\u00e9es)<\/li>\n<\/ul>\n<p><strong>Postuler<\/strong><\/p>\n<ul>\n<li>CV et lettre de motivation.<\/li>\n<li>Mail\u00a0: jobs@esomus.com \/ info@esomus.com<\/li>\n<\/ul>\n","protected":false},"author":1,"featured_media":0,"template":"","meta":{"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"both","_seopress_redirections_param":"","_seopress_redirections_type":301,"_seopress_analysis_target_kw":"","_themeisle_gutenberg_block_has_review":false,"_promoted":"","_job_location":"Li\u00e8ge","_application":"marc.crauwels@esomus.com","_company_name":"Esomus","_company_website":"http:\/\/www.esomus.com","_company_tagline":"","_company_twitter":"","_company_video":"","_filled":0,"_featured":0,"_remote_position":0,"_job_salary":"","_job_salary_currency":"","_job_salary_unit":""},"class_list":["post-5133","job_listing","type-job_listing","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/esomus.com\/index.php\/wp-json\/wp\/v2\/job-listings\/5133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esomus.com\/index.php\/wp-json\/wp\/v2\/job-listings"}],"about":[{"href":"https:\/\/esomus.com\/index.php\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/esomus.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"wp:attachment":[{"href":"https:\/\/esomus.com\/index.php\/wp-json\/wp\/v2\/media?parent=5133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}